{"id":15939,"date":"2014-05-17T15:08:00","date_gmt":"2014-05-17T13:08:00","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=15939"},"modified":"2014-05-17T15:08:00","modified_gmt":"2014-05-17T13:08:00","slug":"i-carabinieri-fermano-tre-tunisini-allinterno-dellauto-trovato-un-fucile-importato-clandestinamente","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2014\/05\/17\/i-carabinieri-fermano-tre-tunisini-allinterno-dellauto-trovato-un-fucile-importato-clandestinamente\/","title":{"rendered":"I carabinieri fermano tre tunisini: all&#8217;interno dell&#8217;auto trovato un fucile importato clandestinamente"},"content":{"rendered":"<p style=\"text-align: justify;\">I militari della Stazione Carabinieri di Santa Croce Camerina hanno trovato e sequestrato un\u2019arma clandestina e denunciato i tre stranieri che l&#8217;avevano in auto. Alcune notti or sono i militari santacrocesi erano impegnati in una perlustrazione delle campagne per prevenire e reprimere i furti in aziende agricole che saltuariamente colpiscono, anche in maniera grave, gli addetti a un settore gi\u00e0 fortemente provato dalla crisi del comparto. Ad un certo punto un\u2019autopattuglia dell\u2019arma nota una station wagon di colore verde. Anche il conducente vede i carabinieri e ha un quasi impercettibile sussulto. I due militari per\u00f2 lo colgono e decidono di fermare il mezzo e controllare i tre occupanti. Sono tre tunisini, tutti incensurati. Ma dal portabagagli salta fuori un fucile. Una carabina a canna rigata di fabbricazione tedesca del calibro 4,5 ad aria compressa. L\u2019arma \u00e8 catalogata anche in Italia tra quelle inferiori ai 7,5 Joule, quindi di libera vendita anche a chi non ha licenza di porto di fucile. Ma subito ai militari \u00e8 balzato all\u2019occhio che tale arma fosse proprio \u201cnuda e cruda\u201d ovvero non avesse n\u00e9 numero di matricola, n\u00e9 numero di catalogo, n\u00e9 punzonature del Banco di prova, unica autorit\u00e0 preposta a dare un \u201clasciapassare\u201d alle armi importate mediante, appunto, un marchio punzonato sulla culatta. I tre cadono dalle nuvole e non sanno dare spiegazioni. Vengono portati in caserma e compiutamente identificati: sono tre agricoltori tunisini di 36, 28 e 54 anni, incensurati. I militari, non avendo una perizia balistica sull\u2019arma, mandano i tre a piede libero ma con le pesanti accuse di detenzione e porto in concorso di arma clandestina illegalmente importata dall\u2019estero e ricettazione in concorso. Reati per cui si rischiano diversi anni di reclusione. Il fucile \u00e8 stato ovviamente sequestrato e sono in corso indagini volte a capire come sia arrivato in provincia di Ragusa.<\/p>\n<p style=\"text-align: right;\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I militari della Stazione Carabinieri di Santa Croce Camerina hanno trovato e sequestrato un\u2019arma clandestina e denunciato i tre stranieri che l&#8217;avevano in auto. Alcune notti or sono i militari santacrocesi erano impegnati in una perlustrazione delle campagne per prevenire e reprimere i furti in aziende agricole che saltuariamente colpiscono, anche in maniera grave, gli [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":15940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[],"class_list":["post-15939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-news"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/15939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=15939"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/15939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/15940"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=15939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=15939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=15939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}