{"id":19762,"date":"2014-09-19T13:06:26","date_gmt":"2014-09-19T11:06:26","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=19762"},"modified":"2014-09-19T13:06:26","modified_gmt":"2014-09-19T11:06:26","slug":"barone-costretto-a-spogliare-s-croce-delle-sue-opere-forse-e-colpa-delle-critiche-sui-social","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2014\/09\/19\/barone-costretto-a-spogliare-s-croce-delle-sue-opere-forse-e-colpa-delle-critiche-sui-social\/","title":{"rendered":"Barone costretto a spogliare S.Croce delle sue opere: &#8220;Forse \u00e8 colpa delle critiche sui social&#8230;&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Da circa venti giorni sono state rimosse tutte le opere che il maestro-artigiano Antonino Barone aveva donato alla citt\u00e0 e che erano posizionate in punti strategici del paese. Anche la statua di Montalbano \u00e8 stata rimossa dalla piazzetta all\u2019ingresso di Punta Secca. Abbiamo voluto sentire dalla viva voce di Barone cosa fosse mai potuto accadere per un cambio di rotta cos\u00ec repentino da parte degli organi istituzionali del Comune di Santa Croce. &#8220;Francamente non me lo so spiegare &#8211; ammette\u00a0 amareggiato -. Ho cercato di sapere, capire, ma il dirigente dell\u2019ufficio tecnico, l\u2019architetto Mormina, mi ha risposto che il permesso per le esposizioni scadeva il 31 agosto e che quindi, dovevo rimuovere il tutto. Ho fatto notare alla dirigente che non mi risultava alcuna scadenza di concessione, ma non sono riuscito a sapere altro. E&#8217; inspiegabile, nessuno degli amministratori si \u00e8 fatto sentire per spiegarmi, nemmeno il Sindaco che pure mi aveva autorizzato ed era entusiasta per le donazioni e del regalo che avevo fatto alla mia citt\u00e0 che adoro e amo. Sono deluso del comportamento di chi ci governa, ma nello stesso tempo auspico che le mie creazioni ritornino presto al loro posto. In fondo non avevo chiesto niente, non ho ricevuto niente. Tutto \u00e8 stato prodotto e posizionato a costo zero per le casse del Comune. Continuo ad essere perplesso, la cagnara che si \u00e8 scatenata per effetto della statua di Montalbano forse ha inciso su questa decisione presa dagli amministratori. Poche persone hanno criticato il \u201clavoro\u201d mentre la statua \u00e8 risultata oggetto di foto e riprese video da parte di un numero considerevole di turisti che evidentemente hanno apprezzato, a differenza di qualcuno. Questi sono fatti e non chiacchiere da Social. La mia vena artistica \u00e8 nata fin dai tempi delle scuole medie. Il compianto prof. Panebianco, all\u2019epoca insegnante di Educazione Artistica, mi ha spinto a coltivare questa mia passione che nel corso degli anni \u00e8 cresciuta e si \u00e8 affinata, fino a creare le opere\u00a0 in oggetto, frutto di duro lavoro e di nottate, tempo sottratto al mio lavoro di fabbro. Lavorare l\u2019acciaio inossidabile non \u00e8 uno scherzo: con grande esborso economico ho realizzato e concretizzato le mie passioni artistiche, senza voler dimostrare niente a nessuno, semplicemente dare sfogo alle mie emozioni nel creare qualcosa&#8221;. Insomma, da questa chiacchierata viene fuori uno spaccato di uomo e artista orgoglioso delle sue origini e delle sue passioni, gratificato dalle esposizioni pubbliche delle sue opere, ed ora, dopo questa vicenda per certi versi grottesca, avvilito, ma speranzoso di poter ancora essere utile alla comunit\u00e0 santacrocese. &#8220;La stragrande maggioranza\u00a0 mi stima e mi spinge a non mollare\u201d spiega Barone. Con questo auspicio termina questo incontro con colui che, per una buon fetta dell\u2019estate appena trascorsa, ha monopolizzato le discussioni sui media e sui social-network. In bocca al lupo, umile artista-artigiano-uomo, orgoglioso e fiero di essere santacrocese.<\/p>\n<p style=\"text-align: right;\"><strong>\u00a0Salvo Dimartino<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/statua.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19764 lazyload\" title=\"statua\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/statua-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/statua-300x225.jpg 300w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/statua-768x576.jpg 768w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/statua-1024x768.jpg 1024w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/statua-86x64.jpg 86w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/staua-3.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-19765 lazyload\" title=\"staua 3\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/staua-3-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/staua-3-300x225.jpg 300w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/staua-3-768x576.jpg 768w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/staua-3-1024x768.jpg 1024w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2014\/09\/staua-3-86x64.jpg 86w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da circa venti giorni sono state rimosse tutte le opere che il maestro-artigiano Antonino Barone aveva donato alla citt\u00e0 e che erano posizionate in punti strategici del paese. Anche la statua di Montalbano \u00e8 stata rimossa dalla piazzetta all\u2019ingresso di Punta Secca. Abbiamo voluto sentire dalla viva voce di Barone cosa fosse mai potuto accadere [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":19763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,1,11],"tags":[],"class_list":["post-19762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-news","category-primopiano"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/19762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=19762"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/19762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/19763"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=19762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=19762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=19762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}