{"id":23477,"date":"2014-12-15T16:31:24","date_gmt":"2014-12-15T15:31:24","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=23477"},"modified":"2014-12-15T16:33:34","modified_gmt":"2014-12-15T15:33:34","slug":"ragusa-i-dipendenti-del-consorzio-di-bonifica-protestano-per-il-mancato-pagamento-di-4-mensilita","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2014\/12\/15\/ragusa-i-dipendenti-del-consorzio-di-bonifica-protestano-per-il-mancato-pagamento-di-4-mensilita\/","title":{"rendered":"<font color='red'> Ragusa &#8211;<\/font> I dipendenti del Consorzio di bonifica protestano per il mancato pagamento di 4 mensilit\u00e0"},"content":{"rendered":"<p style=\"text-align: justify;\">I dipendenti del Consorzio di Bonifica di Ragusa hanno protestato davanti alla Prefettura per il mancato pagamento di 4 mensilit\u00e0 dello stipendio e per avere certezze circa il loro futuro alla luce del progetto di riforma degli enti in Sicilia. Una delegazione di lavoratori e i rappresentanti delle organizzazioni sindacali hanno incontrato il prefetto di Ragusa Annunziato Vard\u00e8 per rappresentargli il loro stato di malessere. Il rappresentante del governo ha avuto un colloquio telefonico col governatore siciliano Rosario Crocetta per chiedergli l&#8217;accreditamento delle somme della seconda semestralit\u00e0 dei contributi ai Consorzi di bonifica che risultano gi\u00e0 impegnate. Crocetta ha rassicurato il prefetto di Ragusa circa un suo personale interessamento per sbloccare la situazione e consentire cos\u00ec il pagamento degli stipendi ai dipendenti. (Ansa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dipendenti del Consorzio di Bonifica di Ragusa hanno protestato davanti alla Prefettura per il mancato pagamento di 4 mensilit\u00e0 dello stipendio e per avere certezze circa il loro futuro alla luce del progetto di riforma degli enti in Sicilia. Una delegazione di lavoratori e i rappresentanti delle organizzazioni sindacali hanno incontrato il prefetto di [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-23477","post","type-post","status-publish","format-standard","hentry","category-breaking"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/23477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=23477"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/23477\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=23477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=23477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=23477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}