{"id":26364,"date":"2015-03-01T16:23:11","date_gmt":"2015-03-01T15:23:11","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=26364"},"modified":"2015-03-02T01:24:02","modified_gmt":"2015-03-02T00:24:02","slug":"basket-c-reg-la-vigor-schianta-marsala-e-ritrova-la-seconda-posizione","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2015\/03\/01\/basket-c-reg-la-vigor-schianta-marsala-e-ritrova-la-seconda-posizione\/","title":{"rendered":"Basket, C reg.: la Vigor schianta Marsala e ritrova la seconda posizione"},"content":{"rendered":"<p style=\"text-align: justify;\">La Emmolo Vigor riaggancia il Basket Gravina al secondo posto in classifica. I camarinensi si presentano al Panatletico di Marsala con una grande voglia di riscattare la sconfitta casalinga subita contro il CUS Catania. Ma l\u2019inizio non \u00e8 dei migliori, con gli uomini di coach Di Stefano che pur portandosi avanti di nove punti, stentano a trovarsi in attacco, con errori spesso banali, e subiscono gli uno contro uno degli avversari con troppa facilit\u00e0. Susino nel primo quarto intraprende un duello titanico con Frisella e anima il pitturato con dei canestri importanti. Ma nel secondo quarto Gangarossa sale in cattedra capovolgendo con le sue triple il punteggio (il parziale finisce 23-19 per la squadra di casa). Giacomo Rizzo e Giorgio Distefano provano a rallentare l\u2019irruenza della guardia marsalese, ma non sempre con esito positivo. Si va dunque all\u2019intervallo lungo con coach Di Stefano visibilmente preoccupato. Nel terzo quarto il carico di falli accumulato da Gangarossa costringe coach Cardillo a richiamarlo in panchina ed il Marsala scende di tono. La\u00a0Emmolo Vigor con grande attenzione riesce a concretizzare bene in contropiede. Anche la mira al tiro da tre punti migliora. Mirko Mandar\u00e0, che nelle ultime gare sta dimostrando continuit\u00e0 di prestazione, si rende utile alla causa. Spazio anche per il febbricitante Paolo Di Stefano che come sempre ha grande voglia di mettersi in evidenza. La serata \u00e8 resa pi\u00f9 felice dalla sconfitta del Basket Gravina sul campo di Giarre. I camarinensi ritornano secondi in classifica e continuano a sognare una delle tre posizioni che vale l&#8217;accesso alla Serie C unica. &#8220;La mia squadra \u2013 dichiara coach Di Stefano \u2013 \u00e8 partita un po\u2019 disattenta. Ho dovuto chiamare qualche time-out di troppo per parlare con i ragazzi e cercare di capire cosa non andasse. Sicuramente non avevamo digerito ancora la beffa subita domenica scorsa. Comunque siamo stati bravi nel terzo quarto a non disunirci e ritrovare il bandolo\u00a0della matassa. Occhipinti, Rizzo e capitan Distefano, coadiuvati dai soliti generosi Lorenzo Mandar\u00e0 e Giovanni Pace, hanno trovato le contromisure agli indemoniati Gangarossa e Frisella&#8221;. Domenica prossima grande attesa per l\u2019arrivo della PGS Sales, che nonostante la sua umile posizione in classifica, schiera in campo un americano ed un senegalese di metri 2.08. Intanto doppio impegno importante per la Video Pi\u00f9 Vigor under 19 che luned\u00ec sera sar\u00e0 impegnata nel derby contro il Basket Club Rg e mercoled\u00ec giocher\u00e0 in casa contro l\u2019Aretusa Siracusa alle 18.00.<\/p>\n<p style=\"text-align: justify;\"><strong>IL TABELLINO<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Marsala 64 &#8211; Emmolo S. &amp; C. srl Vigor 91<\/strong><\/p>\n<div style=\"text-align: justify;\"><strong>Vigor:<\/strong> Mandar\u00e0 Lorenzo 10\u00a0 \u2013 Pace 14 \u2013 Susino 9\u00a0 \u2013 Occhipinti 10\u00a0\u00a0 \u2013 Distefano Giorgio 21 \u2013 Emmolo 4 \u00a0\u00a0\u2013 Di Stefano Paolo\u00a0\u00a0 \u2013 Rizzo Giacomo\u00a0 15\u00a0 &#8211; Mandar\u00e0 Mirko 8<\/div>\n<h2 style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #ff0000;\"><strong><a style=\"color: #ff0000; text-decoration: underline;\" href=\"http:\/\/www.fip.it\/risultati.asp?IDRegione=SO&amp;com=RSO&amp;IDProvincia=PA\">I RISULTATI DELLA GIORNATA<\/a><\/strong><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>La Emmolo Vigor riaggancia il Basket Gravina al secondo posto in classifica. I camarinensi si presentano al Panatletico di Marsala con una grande voglia di riscattare la sconfitta casalinga subita contro il CUS Catania. Ma l\u2019inizio non \u00e8 dei migliori, con gli uomini di coach Di Stefano che pur portandosi avanti di nove punti, stentano [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":23080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-26364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/26364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=26364"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/26364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/23080"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=26364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=26364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=26364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}