{"id":2728,"date":"2013-03-10T13:37:07","date_gmt":"2013-03-10T12:37:07","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=2728"},"modified":"2013-03-11T18:40:34","modified_gmt":"2013-03-11T17:40:34","slug":"calcio-a-5-c2-il-kamarina-tira-fuori-le-unghia-e-azzanna-il-lentini-7-5-playoff-piu-vicini","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2013\/03\/10\/calcio-a-5-c2-il-kamarina-tira-fuori-le-unghia-e-azzanna-il-lentini-7-5-playoff-piu-vicini\/","title":{"rendered":"Calcio a 5, C2: il Kamarina tira fuori le unghie e azzanna il Lentini (7-5). Playoff pi\u00f9 vicini"},"content":{"rendered":"<p style=\"text-align: justify;\">Il CS Kamarina, nel campionato di serie C2 di calcio a cinque, vince contro il Santa Tecla Lentini e compie un deciso passo avanti verso i play off. La squadra di Peppe Marino, seppur non giocando una gara eccelsa, ha avuto la meglio contro i \u201cleontini\u201d che arrivati a Santa Croce con soli sei elementi in distinta, hanno dato del \u201cfilo da torcere\u201d fino alle ultime battute della partita. Il punteggio finale di 7-5, racconta, infatti, di una gara sempre in equilibrio fino a sette minuti dalla fine dell\u2019incontro, momento nel quale l\u2019accoppiata Sammito-Incorvaia, quattro reti per il primo e doppietta per il secondo, decideva di dare una scossa all\u2019incontro. I due giocatori camarinensi, infatti, sul punteggio di 4-4, confezionavano alcune belle giocate che mettevano in ginocchio la flebile difesa ospite e la costringevano a soccombere per ben tre volte. Era il vantaggio decisivo che spostava le sorti dell\u2019incontro verso la squadra di Peppe Marino che con i tre punti conquistati, agganciava al quarto posto l\u2019Imbr\u00f2 Meraco Siracusa e metteva una seria ipoteca alla disputa degli spareggi per la promozione in serie C1. I biancazzurri, comunque, non possono ancora adagiarsi, perch\u00e9 a due giornate dalla fine della regular season i verdetti non sono ancora del tutto definiti e per stilare gli accoppiamenti, si dovr\u00e0 attendere l\u2019ultima gara di campionato. Per questo motivo, la squadra cara al presidente Giovanni Iurato dovr\u00e0 essere accorta a non perdere terreno, cercando di conquistare quanti pi\u00f9 punti degli ultimi sei a disposizione. I camarinensi nel prossimo turno affronteranno, sempre in casa, il fanalino di coda Gymnica Scordia, ma nell\u2019ultima giornata di campionato dovranno far visita alla NBI Misterbianco che lotta, insieme alla Trinacria Gela, per aggiudicarsi la promozione diretta nel campionato di serie C1.<\/p>\n<p style=\"text-align: right;\"><strong>Fabio Fichera<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2013\/03\/155971_447022108695937_130876074_n1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2730 lazyload\" title=\"155971_447022108695937_130876074_n[1]\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2013\/03\/155971_447022108695937_130876074_n1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2013\/03\/155971_447022108695937_130876074_n1-300x225.jpg 300w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2013\/03\/155971_447022108695937_130876074_n1-768x576.jpg 768w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2013\/03\/155971_447022108695937_130876074_n1-86x64.jpg 86w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2013\/03\/155971_447022108695937_130876074_n1.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il CS Kamarina, nel campionato di serie C2 di calcio a cinque, vince contro il Santa Tecla Lentini e compie un deciso passo avanti verso i play off. La squadra di Peppe Marino, seppur non giocando una gara eccelsa, ha avuto la meglio contro i \u201cleontini\u201d che arrivati a Santa Croce con soli sei elementi [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":2729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[],"class_list":["post-2728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-sport"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=2728"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/2728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/2729"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=2728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=2728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=2728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}