{"id":29747,"date":"2015-07-07T11:28:38","date_gmt":"2015-07-07T09:28:38","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=29747"},"modified":"2015-07-07T11:28:38","modified_gmt":"2015-07-07T09:28:38","slug":"modica-masturbatore-seriale-nel-quartiere-sorda-la-polizia-cerca-di-risalire-alla-sua-identita","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2015\/07\/07\/modica-masturbatore-seriale-nel-quartiere-sorda-la-polizia-cerca-di-risalire-alla-sua-identita\/","title":{"rendered":"<font color=red>Modica &#8211;<\/font color> Masturbatore seriale nel quartiere Sorda, la Polizia cerca di risalire alla sua identit\u00e0"},"content":{"rendered":"<p style=\"text-align: justify;\">Un anziano signore \u00e8 stato notato a bordo di un\u2019auto a Modica in una zona del quartiere Sorda frequentata da ragazzini mentre si masturbava. La polizia ha ricevuto alcune segnalazioni da parte dei residenti della zona e sta indagando per cercare di risalire all\u2019identit\u00e0 dell\u2019anziano.Un episodio analogo a quello accaduto tempo fa che aveva avuto come protagonista un altro modicano, un giovane, che compiva lo stesso atto davanti alle scuole. In quel caso le forze dell\u2019ordine hanno individuato il soggetto. Adesso si spera che presto si possa fermare anche quest\u2019uomo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un anziano signore \u00e8 stato notato a bordo di un\u2019auto a Modica in una zona del quartiere Sorda frequentata da ragazzini mentre si masturbava. La polizia ha ricevuto alcune segnalazioni da parte dei residenti della zona e sta indagando per cercare di risalire all\u2019identit\u00e0 dell\u2019anziano.Un episodio analogo a quello accaduto tempo fa che aveva avuto [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":29748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-29747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/29747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=29747"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/29747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/29748"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=29747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=29747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=29747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}