{"id":37651,"date":"2016-04-29T12:52:24","date_gmt":"2016-04-29T10:52:24","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=37651"},"modified":"2016-04-29T12:59:17","modified_gmt":"2016-04-29T10:59:17","slug":"ritrovata-dai-carabinieri-la-ragazzina-minorenne-allontanatasi-da-casa-lo-scorso-25-aprile","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2016\/04\/29\/ritrovata-dai-carabinieri-la-ragazzina-minorenne-allontanatasi-da-casa-lo-scorso-25-aprile\/","title":{"rendered":"<font color=red>Vittoria &#8211;<\/font color> Ritrovata dai Carabinieri la ragazzina minorenne allontanatasi da casa lo scorso 25 Aprile"},"content":{"rendered":"<p style=\"text-align: justify;\">Ha avuto un esito positivo la vicenda della ragazzina minorenne scomparsa da Vittoria lo scorso 25 aprile, e ritrovata a Catania nella nottata di oggi dai militari dell\u2019Arma.\u00a0La giovane si era allontanata da casa senza lasciare traccia e, cos\u00ec come raccontato dalla madre, aveva trascorso la Festivit\u00e0 in compagnia di alcuni coetanei: ma invece di rientrare, aveva fatto perdere le proprie tracce, tanto che la madre nella mattinata di ieri ne aveva denunciato l\u2019allontanamento volontario.<\/p>\n<p style=\"text-align: justify;\">Immediatamente era stato attivato un piano di ricerche, coordinata dalla Prefettura di Ragusa, inoltrando a tutte le Stazioni Carabinieri d\u2019Italia e ai presidi delle altre FF.PP.\u00a0 una foto della diciassettenne, con una descrizione somatica e degli indumenti che indossava al momento dell\u2019allontanamento.<\/p>\n<p style=\"text-align: justify;\">Fortunatamente nella nottata di oggi una pattuglia ha incrociato a Catania nei pressi della stazione ferroviaria la ragazzina: subito riconosciuta, dopo le formalit\u00e0 di rito che hanno consentito di appurare le sue buone condizioni fisiche escludendo che la giovane avesse subito violenze o avesse fatto uso di stupefacenti, \u00e8 stata riaffidata alla madre.\u00a0E\u2019 proprio il caso di dirlo: tutto \u00e8 bene quel che finisce bene!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha avuto un esito positivo la vicenda della ragazzina minorenne scomparsa da Vittoria lo scorso 25 aprile, e ritrovata a Catania nella nottata di oggi dai militari dell\u2019Arma.\u00a0La giovane si era allontanata da casa senza lasciare traccia e, cos\u00ec come raccontato dalla madre, aveva trascorso la Festivit\u00e0 in compagnia di alcuni coetanei: ma invece di [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":37652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-37651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/37651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=37651"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/37651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/37652"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=37651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=37651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=37651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}