{"id":38988,"date":"2016-06-10T08:07:27","date_gmt":"2016-06-10T06:07:27","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=38988"},"modified":"2016-06-10T09:11:39","modified_gmt":"2016-06-10T07:11:39","slug":"abbandono-rifiuti-monito-di-fare-ambiente-serve-piu-senso-civico","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2016\/06\/10\/abbandono-rifiuti-monito-di-fare-ambiente-serve-piu-senso-civico\/","title":{"rendered":"Abbandono rifiuti, monito di Fare Ambiente: &#8220;Serve pi\u00f9 senso civico&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Il fenomeno dell\u2019abbandono dei rifiuti sulle strade da parte di ignoti, si riscontra all\u2019ordine del giorno in varie regioni della nostra Penisola, anche in Sicilia e, in particolare, nelle borgate a mare del comune di Santa Croce Camerina. I lavoratori del servizio di raccolta, dopo aver fatto il proprio dovere in localit\u00e0 Casuzze, hanno commentato su Facebook gli enormi cumuli di rifiuti di vario genere e il disappunto e la sollecitazione di cittadini e abitanti delle zone interessate, che segnalano tempestivamente situazioni simili auspicando che chi di dovere, dal canto suo, adotti le misure necessarie per reprimere l\u2019incivilt\u00e0 e si adoperi per ripristinare lo stato dei luoghi. Fare Ambiente da anni combatte il fenomeno incivile e insalubre, con attivit\u00e0 di prevenzione o cos\u00ec come \u00e8 successo in alcuni casi di repressione con la denuncia presso il comando della Polizia Municipale.<\/p>\n<p style=\"text-align: justify;\">&#8220;Il degrado ambientale \u00e8 punibile con\u00a0l\u2019articolo 192 del decreto legislativo 3 aprile 2006, n.152 che vieta l\u2019abbandono e il deposito incontrollato di rifiuti sul suolo e nel suolo e l\u2019immissione di rifiuti di qualsiasi genere, allo stato solido o liquido, nelle acque superficiali o sotterranee. \u00a0Cosi come \u00e8 vietata &#8211; continua Fare Ambiente &#8211; \u00a0l&#8217;immissione di rifiuti di qualsiasi genere, allo stato solido o liquido, nelle acque superficiali e sotterranee.\u00a0Il sindaco Franca Iurato dispone come ogni anno l&#8217;ordinanza di divieto di abbandonare rifiuti di qualsiasi genere, ma soprattutto confida nel buon senso e nel senso civico di ognuno di noi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il fenomeno dell\u2019abbandono dei rifiuti sulle strade da parte di ignoti, si riscontra all\u2019ordine del giorno in varie regioni della nostra Penisola, anche in Sicilia e, in particolare, nelle borgate a mare del comune di Santa Croce Camerina. I lavoratori del servizio di raccolta, dopo aver fatto il proprio dovere in localit\u00e0 Casuzze, hanno commentato [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":38989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-38988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/38988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=38988"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/38988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/38989"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=38988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=38988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=38988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}