{"id":45489,"date":"2016-12-15T14:23:27","date_gmt":"2016-12-15T13:23:27","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=45489"},"modified":"2016-12-15T14:23:27","modified_gmt":"2016-12-15T13:23:27","slug":"calci-e-pugni-alle-auto-in-corsa-fermato-un-50enne-santacrocese-ubriaco","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2016\/12\/15\/calci-e-pugni-alle-auto-in-corsa-fermato-un-50enne-santacrocese-ubriaco\/","title":{"rendered":"Calci e pugni alle auto in corsa: fermato un 50enne santacrocese ubriaco"},"content":{"rendered":"<p style=\"text-align: justify;\">La segnalazione di un uomo che chiede aiuto in mezzo alla strada, a S. Croce Camerina all\u2019incrocio tra la SP. 85 e la SP. 102, e l\u2019intervento sul posto di una pattuglia dei carabinieri della Stazione di S. Croce Camerina e del commissariato di PS di Comiso; tutto fa presagire un intervento per soccorso che invece si trasforma in una scena da film. L\u2019uomo, visibilmente ubriaco, ferma le autovetture in circolazione e le danneggiava con calci e pugni urlando frasi senza senso. L\u2019arrivo di Carabinieri e Polizia non serve per\u00f2 a calmarlo tanto che lo stesso inizia a correre in mezzo alla strada buia creando serio pericolo per s\u00e9 e per gli automobilisti in transito ed inveendo contro le pattuglie. Dopo un non facile intervento gli operatori riescono a fermarlo e sia un carabiniere che un agente di p.s., presi di mira dai calci e dai pugni dell\u2019uomo riportano lesioni con prognosi di 15 e 10 giorni. L\u2019uomo portato in caserma ed ancora in preda al delirio dell\u2019ubriachezza viene arrestato per resistenza a pubblico ufficiale\u00a0e denunciato per oltraggio a p.u.. \u00a0Si tratta di un 50enne incensurato, che si trova ai domiciliari presso la sua abitazione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La segnalazione di un uomo che chiede aiuto in mezzo alla strada, a S. Croce Camerina all\u2019incrocio tra la SP. 85 e la SP. 102, e l\u2019intervento sul posto di una pattuglia dei carabinieri della Stazione di S. Croce Camerina e del commissariato di PS di Comiso; tutto fa presagire un intervento per soccorso che [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":45490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11],"tags":[],"class_list":["post-45489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primopiano"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=45489"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/45490"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=45489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=45489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=45489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}