{"id":52868,"date":"2017-10-29T10:11:56","date_gmt":"2017-10-29T09:11:56","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=52868"},"modified":"2017-10-29T10:11:56","modified_gmt":"2017-10-29T09:11:56","slug":"unitre-lunedi-verra-inaugurato-lanno-accademico-appuntamento-alle-17","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2017\/10\/29\/unitre-lunedi-verra-inaugurato-lanno-accademico-appuntamento-alle-17\/","title":{"rendered":"Unitre, luned\u00ec verr\u00e0 inaugurato l&#8217;anno accademico: appuntamento alle 17"},"content":{"rendered":"<p style=\"text-align: justify;\">Si terr\u00e0 luned\u00ec 30 ottobre alle 17 l\u2019inaugurazione del nuovo anno accademico dell\u2019Unitre, nella sede del Centro Sociale \u201cTerza Primavera\u201d in via G. Iozzia. Tutta la cittadinanza \u00e8 invitata a partecipare. L\u2019evento si svolger\u00e0 come riportato di seguito:<br \/>\n&#8211; Saluto della Presidente Vitale Maria Rosa e delle Autorit\u00e0 locali;<br \/>\n&#8211; Presentazione dei corsi, laboratori, conferenze e di tutte le attivit\u00e0 che verranno svolte durante l\u2019Anno Accademico;<br \/>\n&#8211; Presentazione dei docenti e dei programmi;<br \/>\n&#8211; Lectio Magistralis dal titolo \u201cViaggio nella commedia dantesca \u201dtenuta dal professore Giuseppe Di Mari, ordinario di Italiano e Latino presso il liceo classico Tommaso Gargallo di Siracusa ed autore di diversi libri di filosofia, pedagogia, letteratura italiana, saggi critici e opere agiografiche. Dirige due Unitre, tre Associazioni culturali ed il mensile di cultura Aretusa Terzo Millennio. E\u2019 appassionato cultore di studi danteschi e ha all&#8217;attivo 5 libri di poesia. Poi sar\u00e0 la volta del coro Unitre, accompagnato alle tastiere da Filippo La Spisa, diretto dal suo direttore artistico Giorgio Baeli.<\/p>\n<p style=\"text-align: justify;\">Da luned\u00ec 6 novembre, invece, si dar\u00e0 il via al ricco calendario delle attivit\u00e0 curriculari dell\u2019associazione: cori, laboratori, attivit\u00e0 culturali, conferenze, gite, escursioni. &#8220;Tutto ci\u00f2 \u00e8 reso possibile grazie alla sensibilit\u00e0 dei nostri Amministratori, i quali\u00a0mettono a disposizione in comodato d\u2019uso i locali della sede; agli insegnanti, ai relatori che prestano la loro opera gratuitamente; ai componenti del Consiglio Direttivo e a tutti i Soci dell\u2019associazione. Quanti interessati a ricevere ulteriori informazioni sulle attivit\u00e0 dell\u2019Unitre si potranno recare presso la sede nei giorni di luned\u00ec e venerd\u00ec dalle ore 10,00 alle 12,00 e dalle 15,00 alle 21,00&#8221;.<\/p>\n<p><em>CONTATTI<\/em><br \/>\nCell &#8211; <strong>3392138856<br \/>\n<\/strong>facebook: <strong><span style=\"color: #3366ff;\">unitre santa croce camerina<br \/>\n<\/span><\/strong>sito web:\u00a0<span style=\"color: #ff0000;\"><strong>www.unitresantacroce.simplesite.com<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2017\/10\/IMG-20170911-WA0007.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-52869 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2017\/10\/IMG-20170911-WA0007.jpg\" alt=\"\" width=\"720\" height=\"1002\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2017\/10\/IMG-20170911-WA0007.jpg 720w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2017\/10\/IMG-20170911-WA0007-216x300.jpg 216w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si terr\u00e0 luned\u00ec 30 ottobre alle 17 l\u2019inaugurazione del nuovo anno accademico dell\u2019Unitre, nella sede del Centro Sociale \u201cTerza Primavera\u201d in via G. Iozzia. Tutta la cittadinanza \u00e8 invitata a partecipare. L\u2019evento si svolger\u00e0 come riportato di seguito: &#8211; Saluto della Presidente Vitale Maria Rosa e delle Autorit\u00e0 locali; &#8211; Presentazione dei corsi, laboratori, conferenze [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":52872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-52868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culturaespettacolo"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/52868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=52868"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/52868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/52872"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=52868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=52868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=52868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}