{"id":52953,"date":"2017-11-01T02:11:51","date_gmt":"2017-11-01T01:11:51","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=52953"},"modified":"2017-11-01T02:11:51","modified_gmt":"2017-11-01T01:11:51","slug":"santa-croce-piange-nico-il-barman-con-il-sorriso-ci-lascia-ad-appena-33-anni","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2017\/11\/01\/santa-croce-piange-nico-il-barman-con-il-sorriso-ci-lascia-ad-appena-33-anni\/","title":{"rendered":"Santa Croce piange Nico: il barman con il sorriso ci lascia ad appena 33 anni"},"content":{"rendered":"<p style=\"text-align: justify;\">La morte di un uomo comune diventa &#8220;notizia&#8221; solo quando \u00e8 tragica: terrorismo, incidenti e conflitti a fuoco ne sono un esempio lampante. Per questo, oggi, vi scriviamo di un &#8220;fatto&#8221;. Che per una volta un giornalista sceglie di non mediare, forse venendo meno alla sua etica professionale. Poco importa. Un &#8220;fatto&#8221; che riguarda la morte, un uomo comune e la sua capacit\u00e0 \u2013 forte e riconosciuta da tutti \u2013 nel saper trasmettere pensieri belli. Nico non ce l\u2019ha fatta. A 33 anni Rosario Domenico Provenzano ha salutato il resto della compagnia, vittima di un male fulmineo che lo ha stroncato in pochi mesi. I funerali si terranno gioved\u00ec pomeriggio alle 15 nella chiesa Madre.<\/p>\n<p style=\"text-align: justify;\">Nico era il ragazzo della porta accanto, quello con cui parlare di tutto: donne, musica, impegno civile. Era quello che ti faceva sentire a tuo agio con i suoi gesti istrionici e i sorrisi sornioni, mentre ti fissava con lo sguardo pieno di s\u00e9 e un fare sospetto. Sembrava quasi una presa in giro: ma \u00e8 in momenti come quelli (ahi, quanto ci mancano!) che riuscivi a stringere un legame, a trovare il giusto feeling. Nico \u00e8 una bella persona che ha dovuto arrendersi a qualcosa pi\u00f9 grande di lui. Uno di quelli che ti sembra impossibile possano finire cos\u00ec. E invece no. La vita gioca brutti scherzi anche a chi pare imbattibile. Ti strappa inesorabile dagli affetti pi\u00f9 cari senza che tu lo voglia o possa far nulla, se non assistere da spettatore incazzato col mondo.<\/p>\n<p style=\"text-align: justify;\">Nico era innamorato della vita, delle persone, dei gesti quotidiani. Come servire ai tavoli della Cantinita, lo storico locale nel cuore di Marina di Ragusa dove ha lavorato per anni e dove tutti, ma proprio tutti, hanno imparato a conoscerlo e amarlo. Era un posto pazzesco, che trasudava amicizia. Per merito (anche) di Nico, della sua allegria, della sua onest\u00e0, della voglia di fare con tutti due chiacchiere. Gli ultimi mesi sono stati un inferno: ma il viaggio infinito da un ospedale all\u2019altro (l\u2019ultimo, a Patti), la sofferenza provata per quella vita che scivolava via ogni giorno di pi\u00f9, non basteranno mai a cancellare le orme di un uomo buono, a cui il destino non ha voluto bene abbastanza.<\/p>\n<p style=\"text-align: justify;\">Ciao \u201cragazzo\u201d, fatti valere anche l\u00ec!<\/p>\n<p><em>La redazione di Santa Croce Web porge le pi\u00f9 sentite condoglianze alla famiglia.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La morte di un uomo comune diventa &#8220;notizia&#8221; solo quando \u00e8 tragica: terrorismo, incidenti e conflitti a fuoco ne sono un esempio lampante. Per questo, oggi, vi scriviamo di un &#8220;fatto&#8221;. Che per una volta un giornalista sceglie di non mediare, forse venendo meno alla sua etica professionale. Poco importa. Un &#8220;fatto&#8221; che riguarda la [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":52954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,11],"tags":[],"class_list":["post-52953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-primopiano"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/52953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=52953"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/52953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/52954"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=52953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=52953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=52953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}