{"id":53877,"date":"2017-12-07T10:06:16","date_gmt":"2017-12-07T09:06:16","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=53877"},"modified":"2017-12-07T10:06:16","modified_gmt":"2017-12-07T09:06:16","slug":"ragusa-operazione-alto-impatto-della-polizia-di-stato-centinaia-di-controlli-denunce-e-sanzioni","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2017\/12\/07\/ragusa-operazione-alto-impatto-della-polizia-di-stato-centinaia-di-controlli-denunce-e-sanzioni\/","title":{"rendered":"<font color=red>Ragusa &#8211;<\/font> Operazione &#8220;Alto impatto&#8221; della Polizia di Stato: centinaia di controlli. Denunce e sanzioni"},"content":{"rendered":"<p style=\"text-align: justify;\">Su direttiva del Questore di Ragusa, in vista anche delle imminenti festivit\u00e0, gli uomini dell\u2019Ufficio Prevenzione Generale e Soccorso Pubblico hanno portato a termine l\u2019Operazione Alto Impatto che ha interessato le piazze ed i principali centri di aggregazione del capoluogo ibleo.\u00a0 Tre giorni di intensi controlli di natura preventiva e repressiva condotti dalle pattuglie della Sezione Volanti, del Reparto Prevenzione Crimine di Catania e dal Reparto Cinofili che hanno passato al setaccio esercizi pubblici, arterie stradali e luoghi di aggregazione. Venticinque i posti di blocco disposti nei punti strategici finalizzati a prevenire il fenomeno del pendolarismo criminale, posto in essere da pregiudicati provenienti da altre province limitrofe.<\/p>\n<p style=\"text-align: justify;\">In totale sono state sottoposte a controllo 321 persone, 128 autovetture ed oltre mille targhe, controllate tramite l\u2019occhio automatico del sistema Mercurio di cui sono dotate le Volanti di Ragusa che segnala auto rubate o non coperte da valido contratto assicurativo. Proprio durante i controlli il lettore automatico ha segnalato un alert a carico della targa di un furgone. Il mezzo \u00e8 stato immediatamente bloccato ed i successivi accertamenti hanno evidenziato che lo stesso circolava in assenza della prescritta copertura assicurativa.\u00a0 Il mezzo \u00e8 stato immediatamente sequestrato ed il conducente sottoposto alla sanzione amministrativa di oltre 800 euro.<\/p>\n<p style=\"text-align: justify;\">In totale sono state elevate sanzioni amministrative per violazione al codice della strada per un valore di oltre 5 mila euro. Specifici controlli sono stati posti in essere nei pressi dell\u2019autostazione di piazza Zama. Sono stati sottoposti a controllo tutti i passeggeri degli autobus provenienti da fuori provincia compresi i rispettivi bagagli. Diverse le posizioni controllate di cittadini extracomunitari. Un\u2019attenzione particolare \u00e8 stata riservata anche ai principali centri commerciali che in questi giorni sono particolarmente affollati da clienti. Durante le attivit\u00e0 \u00e8 stata sottoposta ad accertamento un\u2019auto con a bordo tre giovani residenti a Vittoria. L\u2019atteggiamento sospetto dei tre ha portato gli agenti ad approfondire il controllo con una perquisizione personale sul posto. L\u2019intuito dei poliziotti si \u00e8 rivelato fondato. Uno dei tre, minorenne, nascondeva infatti una piccola quantit\u00e0 di sostanza stupefacente del tipo marijuana, utilizzata per uso personale. Lo stesso \u00e8 stato segnalato alla locale Prefettura come assuntore e affidato alla custodia dei genitori. Passata a setaccio anche una sala giochi in via Colajanni a Ragusa all\u2019interno della quale sono state controllate circa quaranta persone.<\/p>\n<p style=\"text-align: justify;\">Intensificata anche l\u2019attivit\u00e0 di controllo del rispetto delle prescrizioni imposte a soggetti sottoposti a limitazioni della libert\u00e0 personali o a misure di prevenzione. Un ragusano, sottoposto alla misura degli arresti domiciliari \u00e8 stato denunciato all\u2019Autorit\u00e0 giudiziaria per evasione in quanto risultato assente al controllo degli agenti, con relativa richiesta di aggravamento della misura restrittiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su direttiva del Questore di Ragusa, in vista anche delle imminenti festivit\u00e0, gli uomini dell\u2019Ufficio Prevenzione Generale e Soccorso Pubblico hanno portato a termine l\u2019Operazione Alto Impatto che ha interessato le piazze ed i principali centri di aggregazione del capoluogo ibleo.\u00a0 Tre giorni di intensi controlli di natura preventiva e repressiva condotti dalle pattuglie della [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":53878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-53877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/53877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=53877"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/53877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/53878"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=53877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=53877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=53877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}