{"id":69372,"date":"2020-03-19T16:02:07","date_gmt":"2020-03-19T15:02:07","guid":{"rendered":"http:\/\/www.santacroceweb.com\/giornale1\/?p=69372"},"modified":"2020-03-19T16:10:04","modified_gmt":"2020-03-19T15:10:04","slug":"il-sindaco-aggira-il-divieto-e-intona-la-marcia-di-s-giuseppe-per-strada","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2020\/03\/19\/il-sindaco-aggira-il-divieto-e-intona-la-marcia-di-s-giuseppe-per-strada\/","title":{"rendered":"Il sindaco aggira il divieto e intona la marcia di S.Giuseppe per strada"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Circola da questa mattina, sui social<\/strong>, un video del sindaco Giovanni Barone che, a dispetto della raccomandazione di rimanere a casa, fornita in queste ore (in versione multilingua) ai propri concittadini, vaga per le vie del centro con il flauto in mano, mentre intona la marcia sinfonica di San Giuseppe. Questa attivit\u00e0 non sembra rientrare nelle facolt\u00e0 di un primo cittadino, nonch\u00e9 autorit\u00e0 di pubblica sicurezza, ai tempi del Coronavirus. Alle 12 era in programma un flash mob, ma sui balconi. L&#8217;episodio, invece, si \u00e8 verificato all\u2019angolo fra via Caucana e via Morana, a due passi da piazza Vittorio Emanuele II. Nella stessa zona che il primo cittadino e il suo vice, l\u2019assessore Frasca, negli ultimi giorni avevano presidiato assieme alla polizia municipale per limitare gli spostamenti dei santacrocesi, in ottemperanza al decreto della Presidenza del Consiglio dei Ministri. L\u2019accaduto \u00e8 stato condiviso su Facebook dal consigliere comunale Salvatore Cappello.<\/p>\n<p><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Fsalvatore.cappello%2Fvideos%2F10222953009280358%2F&amp;show_text=1&amp;width=215\" width=\"215\" height=\"1019\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circola da questa mattina, sui social, un video del sindaco Giovanni Barone che, a dispetto della raccomandazione di rimanere a casa, fornita in queste ore (in versione multilingua) ai propri concittadini, vaga per le vie del centro con il flauto in mano, mentre intona la marcia sinfonica di San Giuseppe. Questa attivit\u00e0 non sembra rientrare [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":69373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"class_list":["post-69372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-primopiano"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/69372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=69372"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/69372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/69373"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=69372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=69372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=69372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}