{"id":70370,"date":"2020-05-27T13:18:25","date_gmt":"2020-05-27T11:18:25","guid":{"rendered":"http:\/\/www.santacroceweb.com\/?p=70370"},"modified":"2020-05-27T13:18:25","modified_gmt":"2020-05-27T11:18:25","slug":"il-sindaco-nomina-un-esperto-in-comunicazione-a-5-mila-euro-lanno","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2020\/05\/27\/il-sindaco-nomina-un-esperto-in-comunicazione-a-5-mila-euro-lanno\/","title":{"rendered":"Il sindaco nomina un esperto in comunicazione a 5 mila euro l&#8217;anno"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Un nuovo ingresso nella squadra del sindaco Giovanni Barone.<\/strong> Con un decreto, infatti, il primo cittadino di Santa Croce Camerina ha nominato un esperto in materia di informazione e comunicazione istituzionale: si tratta del signor Sergio Randazzo, giornalista di Video Regione, che avr\u00e0 un compenso di 5 mila euro l\u2019anno. Randazzo aveva curato la comunicazione di Lucio Schembari, principale competitor di Barone, nel corso dell\u2019ultima campagna elettorale (<span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.santacroceweb.com\/index.php\/2017\/05\/14\/schembari-riparte-dai-giovani-io-faccio-lallenatore-duro-attacco-al-pd-foto\/\">qui l&#8217;articolo sulla convention d&#8217;apertura<\/a><\/span>). Come si evidenzia dal decreto, Randazzo dovr\u00e0 supportare \u201cil sindaco nell\u2019espletamento di attivit\u00e0 connesse con le materie rientranti nella sfera delle proprie attribuzioni\u201d. Non percepir\u00e0 un euro fino all\u2019approvazione del Bilancio di previsione (i termini scadono a luglio). Tale incarico, di natura fiduciaria, durer\u00e0 per il resto del mandato di Barone. Nel decreto si legge pure che il sindaco si impegna \u201ca trasmettere annualmente al Consiglio comunale una dettagliata relazione sull\u2019attivit\u00e0 svolta dall\u2019esperto nominato\u201d. Randazzo, a cui va un augurio di buon lavoro da parte della redazione di Santa Croce Web, \u00e8 risultato essere in possesso \u201cdei requisiti e dell\u2019esperienza professionale necessari per lo svolgimento delle suddette attivit\u00e0, essendo iscritto all\u2019Ordine dei giornalisti professionisti della Sicilia dal 2008 ed avendo maturato una consolidata esperienza professionale nell\u2019ambito della comunicazione, svolgendo incarichi di direttore di testate giornalistiche e di responsabile di uffici stampa in svariate pubbliche amministrazioni\u201d.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-70372 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2020\/05\/randazzo.jpg\" alt=\"\" width=\"750\" height=\"430\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2020\/05\/randazzo.jpg 750w, https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2020\/05\/randazzo-300x172.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo ingresso nella squadra del sindaco Giovanni Barone. Con un decreto, infatti, il primo cittadino di Santa Croce Camerina ha nominato un esperto in materia di informazione e comunicazione istituzionale: si tratta del signor Sergio Randazzo, giornalista di Video Regione, che avr\u00e0 un compenso di 5 mila euro l\u2019anno. Randazzo aveva curato la comunicazione [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":70371,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-70370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/70370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=70370"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/70370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/70371"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=70370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=70370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=70370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}