{"id":71418,"date":"2020-08-11T08:26:50","date_gmt":"2020-08-11T06:26:50","guid":{"rendered":"http:\/\/www.santacroceweb.com\/?p=71418"},"modified":"2020-08-11T12:26:54","modified_gmt":"2020-08-11T10:26:54","slug":"consiglio-le-reazioni-barone-piena-soddisfazione-il-pd-sindaco-isolato","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2020\/08\/11\/consiglio-le-reazioni-barone-piena-soddisfazione-il-pd-sindaco-isolato\/","title":{"rendered":"<font color=red>Consiglio, le reazioni.<\/font> Barone: piena soddisfazione. Il Pd: &#8220;Sindaco isolato&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>&#8220;Le cause del ritardo per giungere<\/strong> all\u2019approvazione del Bilancio, sono codificate e note a tutti. Ricordo anche a chi punta sempre il dito che il termine ultimo per l\u2019approvazione era il 30 novembre 2020. Mi incuriosisce \u2013 continua il Sindaco \u2013 come il PD possa continuare la sua azione denigratoria nei confronti di questa Amministrazione, sapendo che in qualunque confronto ne uscirebbe perdente. Loro approvarono il Bilancio il 27 novembre 2015\u201d. Lo ha detto il sindaco Giovanni Barone a margine del Consiglio comunale di ieri sera in cui \u00e8 stato approvato il Bilancio di previsione 2020. &#8220;Considerati i tempi di approvazione, ampiamente in anticipo, vorrei lanciare una sfida alle forze politiche: approviamo il prossimo Bilancio entro la fine dell\u2019anno o al massimo entro gennaio\/febbraio 2021. Dagli uffici comunali preposti ho avuto la garanzia della massima disponibilit\u00e0 ad abbattere i tempi\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Nella nota di palazzo di Citt\u00e0,<\/strong> si evidenzia come nella stanza del sindaco &#8220;si respira a pieni polmoni aria di soddisfazione&#8221; dopo il verdetto dell&#8217;aula. \u00a0\u201cL\u2019impianto del Bilancio della Giunta \u00e8 stato modificato di poco &#8211; ha proseguito Barone -. Continueremo la nostra azione amministrativa e voglio tranquillizzare ancora gli esponenti del PD che chiedono la manutenzione delle strade sul territorio camarinense. Sembra assurdo farlo, ma sono costretto a ricordare loro che la mia amministrazione in tre anni ha investito sulla manutenzione stradale pi\u00f9 di quanto loro ne hanno speso in cinque anni. Il confronto anche qui non regge\u201d.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Il Pd: &#8220;Col nostro emendamento possiamo rifare le strade&#8221;<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">&#8220;Ieri si \u00e8 consumato l&#8217;ennesimo dramma nella maggioranza che sostiene il Sindaco. In consiglio comunale, una parte di essa ha riconosciuto nelle proposte della vera opposizione un motivo per sostenerle. Ha pensato che il paese venisse prima del potere e dell&#8217;arroganza. Con senso di responsabilit\u00e0 abbiamo ottenuto l&#8217;approvazione del nostro emendamento aumentando le risorse per le strade del paese. Adesso \u00e8 possibile rifare il manto alle nostre strade!&#8221;. <strong>Lo scrive in una nota il Partito Democratico,<\/strong> <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.santacroceweb.com\/index.php\/2020\/08\/11\/approvato-il-bilancio-di-previsione-frasca-non-gradisce-vedro-il-sindaco\/\" target=\"_blank\" rel=\"noopener noreferrer\">a poche ore dall&#8217;approvazione del Bilancio<\/a><\/span>. &#8220;Sindaco questa \u00e8 l&#8217;opposizione seria, coerente e responsabile, capace di avere uno sguardo al futuro e capace prestissimo di governare &#8211; prosegue la nota -. Il Bilancio, portato con estremo ritardo, \u00e8 stato votato anche da noi per fornirle lo strumento essenziale per realizzare quel che \u00e8 necessario senza se e senza ma. Senza il bilancio il paese sarebbe finito in malora e sarebbe dovuto venire un commissario ad acta per approvarlo e questo dimostra ancor di pi\u00f9 che lei non e&#8217; pi\u00f9 in condizione di governare ma al limite di galleggiare prendendo acqua da tutte le parti. Noi ci siamo, ci saremo e ci prepariamo per dare un futuro alla nostra comunit\u00e0 come gi\u00e0 abbiamo dimostrato ampiamente con il nostro impegno e la nostra passione politica e civile&#8221;.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Ripartiamo Insieme: i motivi del nostro voto favorevole<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u201cIl Bilancio \u00e8 lo strumento attraverso il quale si danno risposte ai bisogni della collettivit\u00e0 e si pongono in essere le attivit\u00e0 necessarie alla valorizzazione e alla tutela del territorio. Il gruppo Ripartiamo Insieme, pur risiedendo all\u2019opposizione, ha deciso di contribuire alla sua approvazione\u201d. <strong>Inizia cos\u00ec la nota dei consiglieri Piero Mandar\u00e0, Antonella Galuppi e Giovanni Giavatto.<\/strong> \u201cSono diversi i motivi che ci hanno fatto propendere per questa decisione: innanzi tutto l\u2019accoglimento di un nostro emendamento da parte dei tre consiglieri vicini al sindaco (Santodonato, Gravina, Candiano), che hanno aderito alla proposta di rimodulare 83 mila euro, destinandoli ai trasporti e al diritto alla mobilit\u00e0. In secondo luogo, la bocciatura degli emendamenti presentati dal gruppo \u201cLiberi di Scegliere\u201d: alcuni ci sono parsi strumentali e dettati dal risentimento, ormai noto, nei confronti del presidente del Consiglio; altri, invece, tendenti a favorire il loro riferimento in giunta, cio\u00e8 l\u2019assessore Frasca , rimpinguando solo ed \u00a0esclusivamente i capitoli di sua competenza. Cos\u00ec, con grande senso di responsabilit\u00e0, abbiamo assunto una posizione che portasse benefici concreti ai cittadini, piuttosto che arroccarci sull\u2019Aventino. Non siamo la maggioranza del Sindaco, i cui metodi abbiamo da sempre stigmatizzato, ma vogliamo rappresentare un pungolo per l\u2019amministrazione, atto per atto e senza inseguire egoismi politici. La mancata approvazione del Bilancio avrebbe determinato la nomina di un commissario prefettizio e il rischio di scioglimento del Consiglio comunale, ossia l\u2019organo democraticamente eletto. Che, piuttosto, va tutelato\u201d. I consiglieri di Ripartiamo Insieme, infine, evidenziano \u201clo sfaldamento della compagine denominata \u201cLiberi di Scegliere\u201d, che in questi mesi ha disatteso il mandato elettorale \u2013 cio\u00e8 accomodarsi all\u2019opposizione \u2013 e orchestrato ogni genere di inciucio, pretendendo il ritorno dell\u2019assessore Frasca e di altre figure legate a quel mondo. Siamo estranei ai giochi di palazzo che risultano dannosi e incomprensibili per la citt\u00e0. Continueremo ad operare con senso di responsabilit\u00e0 e nella logica del bene comune, l\u2019unica che ci appartiene\u201d.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Liberi di Scegliere: quella della responsabilit\u00e0 \u00e8 una supercazzola<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Liberi di Scegliere, priva di Schembari, ha votato contro dopo la bocciatura di tre emendamenti. <strong>Il capogruppo Agnello sbuffa sui social:<\/strong> &#8220;I consiglieri di Ripartiamo Insieme (i dissidenti) e il Partito Democratico, dopo mesi di attacchi e di inviti ad andarcene tutti a casa all&#8217;Amministrazione Barone, votano s\u00ec al Bilancio, di fatto tenendo (loro) ancora a galla il Sindaco. Seguiranno gustosi approfondimenti (comprese le supercazzole sulla responsabilit\u00e0 bla bla bla)&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Le cause del ritardo per giungere all\u2019approvazione del Bilancio, sono codificate e note a tutti. Ricordo anche a chi punta sempre il dito che il termine ultimo per l\u2019approvazione era il 30 novembre 2020. Mi incuriosisce \u2013 continua il Sindaco \u2013 come il PD possa continuare la sua azione denigratoria nei confronti di questa Amministrazione, [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":70899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[232,141,147],"class_list":["post-71418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-consiglio-comunale","tag-luca-agnello","tag-partito-democratico"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/71418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=71418"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/71418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/70899"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=71418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=71418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=71418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}