{"id":71758,"date":"2020-08-29T16:37:25","date_gmt":"2020-08-29T14:37:25","guid":{"rendered":"http:\/\/www.santacroceweb.com\/?p=71758"},"modified":"2020-08-29T16:37:25","modified_gmt":"2020-08-29T14:37:25","slug":"covid-un-positivo-al-circolo-velico-di-kaukana-sanificati-i-locali","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2020\/08\/29\/covid-un-positivo-al-circolo-velico-di-kaukana-sanificati-i-locali\/","title":{"rendered":"Covid: un &#8220;positivo&#8221; al circolo velico di Kaukana, sanificati i locali"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>In riferimento alla notizia di un positivo<\/strong> tra i soci del Circolo Velico Kaukana, il Sindaco di Santa Croce, Giovanni Barone, dopo un breve consulto con il presidente della struttura estiva, ha deciso di avviare una sanificazione nei locali del circolo velico. L&#8217;Asp ha gi\u00e0 avviato il protocollo sanitario previsto. &#8220;Senza alcun allarmismo &#8211; afferma Barone &#8211; credo sia giunto il momento di applicare rigorosamente tutti protocolli per questa tipologia di attivit\u00e0. Voglio inoltre sensibilizzare tutti i miei concittadini ed i vacanzieri ancora presenti su tutto il nostro territorio, di attenersi scrupolosamente alle direttive nazionali anti-Covid19&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In riferimento alla notizia di un positivo tra i soci del Circolo Velico Kaukana, il Sindaco di Santa Croce, Giovanni Barone, dopo un breve consulto con il presidente della struttura estiva, ha deciso di avviare una sanificazione nei locali del circolo velico. L&#8217;Asp ha gi\u00e0 avviato il protocollo sanitario previsto. &#8220;Senza alcun allarmismo &#8211; afferma [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":71759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11],"tags":[247,329,183,246,156],"class_list":["post-71758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-primopiano","tag-asp","tag-circolo-velico-kaukana","tag-coronavirus","tag-covid","tag-giovanni-barone"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/71758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=71758"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/71758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/71759"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=71758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=71758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=71758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}