{"id":77825,"date":"2022-05-06T17:28:44","date_gmt":"2022-05-06T15:28:44","guid":{"rendered":"https:\/\/www.santacroceweb.com\/?p=77825"},"modified":"2022-05-06T17:31:05","modified_gmt":"2022-05-06T15:31:05","slug":"il-punto-vaccinale-di-santa-croce-chiude-con-quasi-14-mila-dosi","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2022\/05\/06\/il-punto-vaccinale-di-santa-croce-chiude-con-quasi-14-mila-dosi\/","title":{"rendered":"Il punto vaccinale di Santa Croce chiude con quasi 14 mila dosi"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Dopo quasi un anno di attivit\u00e0,<\/strong> chiude il Centro Vaccinale di Santa Croce Camerina. I dati che emergono dall\u2019apertura del Centro, avvenuta il 26 maggio 2021, evidenziano un successo in termini di vaccini somministrati, ben 13.959 dosi. \u201cIn questo anno abbiamo sempre collaborato in modo molto proficuo con ASP7 di Ragusa \u2013 afferma il sindaco Giovanni Barone -. Gli sforzi fatti ci hanno premiato. Innanzitutto i ringraziamenti vanno al Direttore Generale dell\u2019ASP, Arch. Angelo Aliqu\u00f2, al responsabile degli Hub vaccinali in provincia di Ragusa, Dott. Giovanni Ragusa, al Direttore Sanitario dell\u2019ASP, Dott. Raffaele Elia. Ringrazio altres\u00ec \u2013 continua Barone \u2013 tutti i medici e gli infermieri che hanno prestato la loro preziosa opera nel Centro Vaccinale. Un ringraziamento doveroso va anche ai 35 volontari del Sistema Locale di Protezione Civile (AVS &#8211; Gruppo Comunale P.C.) che si sono occupati dell\u2019assistenza agli utenti e della logistica dei due punti vaccinali allestiti, sotto la direzione del Responsabile di Funzione COC Salvatore Traina. Un successo sugellato anche dalle vaccinazioni effettuate anche a tutte quelle persone \u2018fragili\u2019 che difficilmente avrebbero potuto vaccinarsi negli Hub dislocati in varie citt\u00e0 della provincia di Ragusa, compresi gli stranieri irregolari&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>&#8220;In piena fase di emergenza<\/strong> pandemica &#8211; prosegue il sindaco &#8211; abbiamo messo a disposizione fin da subito spazi, risorse economiche e competenze per affrontare una situazione di crisi mai vista prima. Insieme alle autorit\u00e0 sanitarie, alle istituzioni e ai volontari, abbiamo creato in tempi record un Centro vaccinale diventato subito un esempio di efficienza a livello provinciale. La sua chiusura, ora, rappresenta un ulteriore passo verso la normalit\u00e0 e il ritorno a tempo pieno a quella che \u00e8 la nostra mission: organizzare manifestazioni di successo, per i nostri espositori e visitatori\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo quasi un anno di attivit\u00e0, chiude il Centro Vaccinale di Santa Croce Camerina. I dati che emergono dall\u2019apertura del Centro, avvenuta il 26 maggio 2021, evidenziano un successo in termini di vaccini somministrati, ben 13.959 dosi. \u201cIn questo anno abbiamo sempre collaborato in modo molto proficuo con ASP7 di Ragusa \u2013 afferma il sindaco [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":76837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[351,156,805,139],"class_list":["post-77825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-angelo-aliquo","tag-giovanni-barone","tag-punto-vaccinale","tag-santa-croce-camerina"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/77825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=77825"}],"version-history":[{"count":0,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/77825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/76837"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=77825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=77825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=77825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}