{"id":86335,"date":"2026-06-03T19:06:45","date_gmt":"2026-06-03T17:06:45","guid":{"rendered":"https:\/\/www.santacroceweb.com\/?p=86335"},"modified":"2026-07-24T09:50:58","modified_gmt":"2026-07-24T07:50:58","slug":"open-fiber-grazie-ai-cittadini-risolte-le-criticita-segnalate-a-casuzze","status":"publish","type":"post","link":"https:\/\/www.santacroceweb.com\/index.php\/2026\/06\/03\/open-fiber-grazie-ai-cittadini-risolte-le-criticita-segnalate-a-casuzze\/","title":{"rendered":"Open Fiber: \u201cGrazie ai cittadini, risolte le criticit\u00e0 segnalate a Casuzze\u201d"},"content":{"rendered":"<p>Catania, 3 giugno 2026 &#8211; Open Fiber ringrazia i residenti della frazione di Casuzze e la redazione di Santa Croce Web per la segnalazione relativa alle criticit\u00e0 evidenziate nelle vie del Trifoglio e dell\u2019Arancio e desidera porgere le proprie scuse ai cittadini per i disagi arrecati durante le attivit\u00e0 di cantiere.<\/p>\n<p>L\u2019azienda \u00e8 costantemente impegnata a garantire il rispetto dei territori in cui opera e, non appena venuta a conoscenza della situazione segnalata, \u00e8 prontamente intervenuta per la rimozione dei materiali e per il ripristino delle condizioni di pulizia e decoro dell\u2019area interessata dal cantiere di propria competenza.<\/p>\n<p>Tale intervento rientra nell\u2019ambito dei progetti di cablaggio in fibra ottica che Open Fiber ha realizzato nella frazione di Casuzze e nel Comune di Santa Croce Camerina sia con il Piano Banda Ultra Larga sia con il Piano \u2018Italia a 1 Giga\u2019, che hanno permesso di collegare complessivamente oltre 3mila unit\u00e0 immobiliari tra abitazioni, strutture ricettive e alberghiere, piccole e medie imprese e uffici: un\u2019infrastruttura strategica che consentir\u00e0 di migliorare la connettivit\u00e0 del territorio, favorendo l\u2019accesso a servizi digitali avanzati e contribuendo allo sviluppo economico e sociale della comunit\u00e0 locale.<\/p>\n<div id='gallery-1' class='gallery galleryid-86335 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/b68016bf-bd70-4793-be8b-70537d6b91e3.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/b68016bf-bd70-4793-be8b-70537d6b91e3-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/b68016bf-bd70-4793-be8b-70537d6b91e3-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/0f99fa32-82fa-4b8b-9ac3-1f54ff6d5637.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/0f99fa32-82fa-4b8b-9ac3-1f54ff6d5637-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/0f99fa32-82fa-4b8b-9ac3-1f54ff6d5637-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/250f6270-42ee-4606-b9a9-240e8c594928.jpeg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/250f6270-42ee-4606-b9a9-240e8c594928-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/250f6270-42ee-4606-b9a9-240e8c594928-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/229198d2-6c08-4814-bd0a-2fec175d1f96.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/229198d2-6c08-4814-bd0a-2fec175d1f96-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/229198d2-6c08-4814-bd0a-2fec175d1f96-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/a315d308-a250-489b-8751-0e4fe20e3024.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/a315d308-a250-489b-8751-0e4fe20e3024-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/a315d308-a250-489b-8751-0e4fe20e3024-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/fbe25d70-b541-49cc-969d-74ac56c74364.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/fbe25d70-b541-49cc-969d-74ac56c74364-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/fbe25d70-b541-49cc-969d-74ac56c74364-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/48cd8c16-420c-4196-9c93-141d1caa1998.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/48cd8c16-420c-4196-9c93-141d1caa1998-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/48cd8c16-420c-4196-9c93-141d1caa1998-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/809feb60-a9fb-41f4-b15d-35682548325c.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/809feb60-a9fb-41f4-b15d-35682548325c-20x27.jpeg\" class=\"attachment-thumbnail size-thumbnail jl-lazyload lazyload\" alt=\"\" data-src=\"https:\/\/www.santacroceweb.com\/giornale1\/wp-content\/uploads\/2026\/06\/809feb60-a9fb-41f4-b15d-35682548325c-150x150.jpeg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Catania, 3 giugno 2026 &#8211; Open Fiber ringrazia i residenti della frazione di Casuzze e la redazione di Santa Croce Web per la segnalazione relativa alle criticit\u00e0 evidenziate nelle vie del Trifoglio e dell\u2019Arancio e desidera porgere le proprie scuse ai cittadini per i disagi arrecati durante le attivit\u00e0 di cantiere. L\u2019azienda \u00e8 costantemente impegnata [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":86336,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-86335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"_links":{"self":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/86335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=86335"}],"version-history":[{"count":2,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/86335\/revisions"}],"predecessor-version":[{"id":86347,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/posts\/86335\/revisions\/86347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media\/86336"}],"wp:attachment":[{"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=86335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=86335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacroceweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=86335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}